{"id":2581,"date":"2019-06-10T08:56:23","date_gmt":"2019-06-10T06:56:23","guid":{"rendered":"http:\/\/www.npsconsulting-avocats.fr\/NPS\/?p=2581"},"modified":"2019-07-10T09:05:38","modified_gmt":"2019-07-10T07:05:38","slug":"la-gouvernance-des-entreprises-associatives","status":"publish","type":"post","link":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/la-gouvernance-des-entreprises-associatives\/","title":{"rendered":"La gouvernance des entreprises associatives (Juris-Editions, 2019)"},"content":{"rendered":"<p class=\"singleTitre entry-title\"><strong>Les associations investissent de plus en plus la sph\u00e8re \u00e9conomique voire m\u00eame commerciale entra\u00eenant pour bon nombre de ces organismes de nouveaux comportements entrepreneuriaux. Pour autant, plusieurs crit\u00e8res tels que la pr\u00e9sence de b\u00e9n\u00e9voles, la poursuite d\u2019un but non lucratif et son rapport \u00e0 l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral ou l\u2019utilit\u00e9 sociale\u2026 fondent les sp\u00e9cificit\u00e9s de l\u2019entreprise associative. Ce nouvel op\u00e9rateur \u00e9conomique pr\u00e9figure-t-il l\u2019\u00e9mergence d\u2019un nouveau cadre entrepreneurial capable de conjuguer efficacit\u00e9 \u00e9conomique et logique sociale ? Reposant sur une hybridation des ressources (mon\u00e9taires \u2013 non mon\u00e9taires ; publiques \u2013 priv\u00e9es), cette approche du fait associatif impose de nouvelles contraintes en mati\u00e8re de gouvernance tant sur le plan juridique que fiscal. C\u2019est l\u2019ensemble de ces r\u00e8gles que cet ouvrage se propose de d\u00e9tailler.\u00a0<\/strong><\/p>\n<div class=\"entry-content wrapper contenugenerique\">\n<p>\u00a0<a href=\"http:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2019\/07\/couv_1_Bis-pdf.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2583\" src=\"http:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2019\/07\/couv_1_Bis-pdf-237x300.jpg\" alt=\"\" width=\"237\" height=\"300\" \/><\/a><\/p>\n<p>Au cours de ces dix derni\u00e8res ann\u00e9es, les budgets associatifs ont profond\u00e9ment \u00e9volu\u00e9\u00a0: ils continuent de cro\u00eetre de fa\u00e7on r\u00e9guli\u00e8re et constante malgr\u00e9 la forte diminution des financements publics. Quelles sont les nouvelles ressources auxquelles a d\u00e9sormais recours le secteur associatif ? Comment les ma\u00eetriser\u00a0? La r\u00e9alisation d\u2019activit\u00e9s \u00e9conomiques voire m\u00eame commerciales est-elle compatible avec la loi 1901\u00a0? Comment optimiser les mod\u00e8les \u00e9conomiques\u00a0et\/ou modes de fonctionnement de ces entreprises associatives tout en pr\u00e9servant leurs sp\u00e9cificit\u00e9s au regard de la concurrence et de la fiscalit\u00e9 ? Comment gouverner ces nouveaux acteurs \u00e9conomiques\u00a0? Quelles sont les nouvelles contraintes et responsabilit\u00e9s pour les dirigeants associatifs en mati\u00e8re de transparence ou d\u2019\u00e9valuation ? Comment associer l\u2019ensemble des parties prenantes au projet associatif afin de r\u00e9pondre aux exigences de la loi du 31 juillet 2014 relative \u00e0 l\u2019\u00c9conomie sociale et solidaire\u00a0? Autant de sujets n\u00e9cessitant de pr\u00e9ciser des notions aussi importantes que celles d\u2019entreprise, d\u2019activit\u00e9 \u00e9conomique, d\u2019utilit\u00e9 sociale ou encore d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral. En effet, l\u2019interventionnisme \u00e9conomique des associations met en exergue de nouvelles pratiques associatives qu\u2019il convient d\u2019expliciter de fa\u00e7on pratique.<\/p>\n<p>Avec de tr\u00e8s nombreuses illustrations concr\u00e8tes donn\u00e9es par la jurisprudence, cet ouvrage portant sur <em>La gouvernance des entreprises associatives <\/em>montre que le r\u00f4le du secteur associatif dans la r\u00e9ponse apport\u00e9e \u00e0 des besoins sociaux conna\u00eet de profonds bouleversements. Il explore de nombreuses pistes visant \u00e0 optimiser la gestion des associations, tant sur le plan juridique que fiscal. Il s\u2019enrichit d\u2019une analyse approfondie des sp\u00e9cificit\u00e9s de la pratique associative dans la sph\u00e8re \u00e9conomique, qui bat en br\u00e8che un certain nombre d\u2019id\u00e9es re\u00e7ues sur le sujet. Des d\u00e9veloppements sont plus particuli\u00e8rement consacr\u00e9s aux aspects li\u00e9s \u00e0 la restructuration, \u00e0 la construction et l\u2019optimisation de mod\u00e8les \u00e9conomiques associatifs nouveaux.<\/p>\n<p>Pour mieux appr\u00e9hender les \u00e9volutions de ce secteur, <em>La gouvernance des entreprises associatives <\/em>offre un recueil d\u2019informations uniques et indispensables aux acteurs associatifs et \u00e0 leurs partenaires publics et priv\u00e9s.<\/p>\n<p>L\u2019auteur,<strong> <a href=\"http:\/\/www.isbl-consultants.fr\/equipes\/colas-amblard\/\">Colas Amblard<\/a><\/strong>, est docteur en droit, avocat associ\u00e9 du Cabinet NPS consulting et charg\u00e9 d\u2019enseignements \u00e0 l\u2019universit\u00e9 Jean-Moulin Lyon\u00a0III. Auteur d\u2019une th\u00e8se de droit intitul\u00e9e \u00ab\u00a0<em>Associations et activit\u00e9s \u00e9conomiques\u00a0: contribution \u00e0 la th\u00e9orie du tiers secteur\u00a0<\/em>\u00bb, prim\u00e9e en 1998 par l\u2019ADDES et la Fondation CETELEM, il est sp\u00e9cialis\u00e9 depuis vingt ans en droit et fiscalit\u00e9 des institutions sans but lucratif (association, fondation, fonds de dotation, syndicats\u2026). Directeur des publications et Pr\u00e9sident de l\u2019Institut ISBL, il a \u00e9crit de nombreux ouvrages et articles dans le domaine des institutions sans but lucratif (ISBL). En qualit\u00e9 de praticien, il dispose d\u2019une expertise reconnue en mati\u00e8re d\u2019optimisation et de restructuration associative et intervient \u00e0 ce titre sur l\u2019ensemble du territoire national. Il est \u00e9galement conf\u00e9rencier et anime des formations sp\u00e9cialis\u00e9es sur les th\u00e9matiques propres aux ISBL.<\/p>\n<p>Pr\u00e9face de <strong>Karim Mahmoud-Vintam<\/strong>, Fondateur et D\u00e9l\u00e9gu\u00e9 g\u00e9n\u00e9ral des Cit\u00e9s d\u2019Or.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"authorInfo\">\n<div class=\"authorlink\"><\/div>\n<\/div>\n<div class=\"entry-content wrapper contenugenerique\">\n<p><strong>Le 28 ao\u00fbt 2019 para\u00eetra le nouvel ouvrage de <a href=\"http:\/\/www.isbl-consultants.fr\/equipes\/colas-amblard\/\">Colas AMBLARD<\/a> : \u00ab\u00a0<em>La gouvernance des entreprises associatives \u2013 Administration et fonctionnement<\/em>\u00a0\u00bb aux \u00c9ditions Juris.<\/strong><\/p>\n<\/div>\n<h3 class=\"product-title\"><a href=\"https:\/\/livre.fnac.com\/a13562793\/Amblard-Colas-La-gouvernance-des-entreprises-associatives\"><strong>Pr\u00e9-commander ICI<\/strong><\/a><\/h3>\n<\/div>\n<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les associations investissent de plus en plus la sph\u00e8re \u00e9conomique voire m\u00eame commerciale entra\u00eenant pour bon nombre de ces organismes de nouveaux comportements entrepreneuriaux. Pour autant, plusieurs crit\u00e8res tels que la pr\u00e9sence de b\u00e9n\u00e9voles, la poursuite d\u2019un but non lucratif et son rapport \u00e0 l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral ou l\u2019utilit\u00e9 sociale\u2026 fondent les sp\u00e9cificit\u00e9s de l\u2019entreprise associative. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[10,259,313,137,43,161,138,130,126,31,35,77,160,6,37],"class_list":["post-2581","post","type-post","status-publish","format-standard","hentry","category-actualites","tag-association","tag-association-et-avocat","tag-avocat-en-droit-des-associations","tag-avocat-specialise-dans-le-secteur-associatif","tag-colas-amblard","tag-dalloz","tag-droit-des-associations","tag-entreprise-associative","tag-fiscalite-des-associations","tag-gouvernance","tag-interet-general","tag-isbl-consultants","tag-juris-associations","tag-nonprofit-sector","tag-utilite-sociale"],"_links":{"self":[{"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/posts\/2581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/comments?post=2581"}],"version-history":[{"count":2,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/posts\/2581\/revisions"}],"predecessor-version":[{"id":2585,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/posts\/2581\/revisions\/2585"}],"wp:attachment":[{"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/media?parent=2581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/categories?post=2581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/tags?post=2581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}