{"id":2562,"date":"2019-04-30T17:03:48","date_gmt":"2019-04-30T15:03:48","guid":{"rendered":"http:\/\/www.npsconsulting-avocats.fr\/NPS\/?p=2562"},"modified":"2019-04-30T17:03:48","modified_gmt":"2019-04-30T15:03:48","slug":"le-boom-des-recettes-dactivites-quelles-consequences-pour-le-secteur-associatif","status":"publish","type":"post","link":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/le-boom-des-recettes-dactivites-quelles-consequences-pour-le-secteur-associatif\/","title":{"rendered":"Le \u00ab boom \u00bb des recettes d\u2019activit\u00e9s \u2013 Quelles cons\u00e9quences pour le secteur associatif ?"},"content":{"rendered":"<p><a href=\"http:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2010\/06\/Fotolia_95787402_M-2-e1458225514728.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1819\" src=\"http:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2010\/06\/Fotolia_95787402_M-2-e1458225514728-300x100.jpg\" alt=\"\" width=\"300\" height=\"100\" srcset=\"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2010\/06\/Fotolia_95787402_M-2-e1458225514728-300x100.jpg 300w, https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2010\/06\/Fotolia_95787402_M-2-e1458225514728-768x255.jpg 768w, https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2010\/06\/Fotolia_95787402_M-2-e1458225514728-1024x340.jpg 1024w, https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2010\/06\/Fotolia_95787402_M-2-e1458225514728-100x33.jpg 100w, https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2010\/06\/Fotolia_95787402_M-2-e1458225514728-1040x345.jpg 1040w, https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-content\/uploads\/2010\/06\/Fotolia_95787402_M-2-e1458225514728.jpg 1687w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong>Assur\u00e9ment, l\u2019un des faits associatifs les plus marquants de cette nouvelle \u00e9tude r\u00e9side dans le \u00ab\u00a0boom\u00a0\u00bb des recettes d\u2019activit\u00e9s associatives, puisque celles-ci sont <a href=\"https:\/\/www.associations.gouv.fr\/IMG\/pdf\/tchernonog_associations_fcc_2018.pdf\">pass\u00e9es de 49% \u00e0 66% en part de budget cumul\u00e9 du secteur associatif entre 2005 et 2017<\/a>. Les raisons de ce ph\u00e9nom\u00e8ne sont connues\u00a0: diminution des subventions, augmentation du recours \u00e0 la commande publique et des prestations r\u00e9alis\u00e9es au profit des membres et autres usagers. Reste \u00e0 appr\u00e9cier les cons\u00e9quences de cette \u00e9volution dans la pratique associative pour les associations et leurs adh\u00e9rents.<\/strong><\/p>\n<p><!--more--><\/p>\n<h4><strong>L\u2019\u00e9mergence du concept d\u2019entreprise associative<\/strong><\/h4>\n<p>L\u2019article 1er de la loi 1901 d\u00e9finit l\u2019association comme une \u00ab <em>convention par laquelle deux ou plusieurs personnes mettent en commun, d\u2019une fa\u00e7on permanente, leurs connaissances ou leur activit\u00e9 dans un but autre que de partager des b\u00e9n\u00e9fices<\/em> \u00bb. Or, en qualifiant les associations d\u2019 \u00ab<em>organismes \u00e0 but non lucratif<\/em> \u00bb, la doctrine majoritaire a longtemps \u00e9t\u00e9 partisane ou prisonni\u00e8re d\u2019une conception strictement philanthropique du secteur associatif contribuant ainsi \u00e0 propager, au sein du monde associatif lui-m\u00eame, l\u2019id\u00e9e d\u2019une incompatibilit\u00e9 de principe entre les associations et le monde des affaires. Aussi, en entretenant une confusion entre la capacit\u00e9 juridique dont dispose ce type d\u2019organisme et l\u2019interdiction faite \u00e0 ses membres, une telle approche du fait associatif s\u2019est longtemps fond\u00e9e sur une interpr\u00e9tation erron\u00e9e de l\u2019article 1er de la loi 1901. En effet, l\u2019ex\u00e9g\u00e8se de cette disposition l\u00e9gale d\u00e9montre que la contrainte de propri\u00e9t\u00e9 impartageable des b\u00e9n\u00e9fices s\u2019analyse au niveau des membres, ce qui induit <em>a priori <\/em>que le groupement associatif est, quant \u00e0 lui, en droit de r\u00e9aliser des exc\u00e9dents<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<p>Par cons\u00e9quent, rien ne s\u2019oppose d\u00e9sormais \u00e0 ce que l\u2019association \u00e0 caract\u00e8re \u00e9conomique soit reconnue comme une v\u00e9ritable entreprise, ce qui a d\u2019ailleurs \u00e9t\u00e9 confirm\u00e9 \u00e0 deux reprises par le Conseil constitutionnel en 2006 : \u00ab <em>doit \u00eatre regard\u00e9e comme une entreprise<\/em> \u00bb une association \u00ab <em>qui a pour activit\u00e9 principale la prestation de services<\/em> \u00bb<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>. Une telle approche est conforme \u00e0 la jurisprudence europ\u00e9enne<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a> pour qui la notion d\u2019entreprise \u00ab <em>comprend toute entit\u00e9 exer\u00e7ant une activit\u00e9 \u00e9conomique, ind\u00e9pendamment du statut juridique de cette activit\u00e9 et de son mode de fonctionnement<\/em> \u00bb.<\/p>\n<h4><strong><em>Ab initio<\/em><\/strong><strong>, l\u2019entreprise associative ne peut \u00eatre assimil\u00e9e \u00e0 un commer\u00e7ant<\/strong><\/h4>\n<p>Jusqu\u2019alors, la Cour de cassation a toujours affirm\u00e9 qu\u2019une association exer\u00e7ant des activit\u00e9s commerciales m\u00eame \u00e0 titre principal ne saurait \u00eatre assimil\u00e9e \u00e0 un commer\u00e7ant<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a>. En effet, en raison du principe de propri\u00e9t\u00e9 impartageable des b\u00e9n\u00e9fices impos\u00e9 par la loi 1901, une association ne peut avoir un objet statutaire commercial au sens de l\u2019article L. 121-1 du code de commerce et exercer ainsi la profession de commer\u00e7ant. En d\u2019autres termes, la juridiction supr\u00eame confirme que si l\u2019association peut r\u00e9aliser des actes de commerce \u00e0 titre accessoire<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a>, voire habituel<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a>, ceux-ci ne peuvent primer sur son objet statutaire au point d\u2019entra\u00eener une assimilation l\u00e9gale du statut de cette derni\u00e8re avec celui de commer\u00e7ant<a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a>. C\u2019est pr\u00e9cis\u00e9ment la solution retenue par la chambre commerciale du tribunal de grande instance de Strasbourg le 27 ao\u00fbt 2014, d\u00e9cision de premi\u00e8re instance confirm\u00e9e par la Cour d\u2019appel de Grenoble du 13 juin 2017<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a>, jugeant qu\u2019une association organisatrice de plusieurs repr\u00e9sentations artistiques par an, qui d\u00e9tenait une licence d\u2019entrepreneur du spectacle et dont les ressources provenaient principalement de la billetterie et de l\u2019achat\/revente de spectacles, ne pouvait avoir la qualit\u00e9 de commer\u00e7ant, notamment en raison du fait \u00ab <em>qu\u2019elle ne distribue pas de b\u00e9n\u00e9fices, les exc\u00e9dents \u00e9ventuels \u00e9tant r\u00e9affect\u00e9s dans la r\u00e9alisation de l\u2019objet social<\/em> \u00bb. En confirmant la distinction fondamentale entre activit\u00e9 et profession, les juridictions refusent toute id\u00e9e d\u2019une assimilation de principe entre association \u00e0 caract\u00e8re \u00e9conomique et soci\u00e9t\u00e9 commerciale, confirmant au passage l\u2019h\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 des modes d\u2019entreprendre en France.<\/p>\n<p>La confrontation de la notion d\u2019activit\u00e9 \u00e9conomique avec celle d\u2019activit\u00e9 commerciale (ou lucrative)<a href=\"#_ftn9\" name=\"_ftnref9\">[9]<\/a> permet, \u00e9galement, d\u2019op\u00e9rer une distinction entre, d\u2019une part, les activit\u00e9s associatives et, d\u2019autre part, le but de l\u2019association. Cette distinction entre activit\u00e9s et but du groupement d\u00e9montre l\u2019existence d\u2019entreprises capables de r\u00e9aliser des op\u00e9rations \u00e0 titre on\u00e9reux, tout en conservant un objectif qui, lui, demeure non lucratif. Or, aujourd\u2019hui, c\u2019est pr\u00e9cis\u00e9ment cette sp\u00e9cificit\u00e9 qui fonde l\u2019appartenance des associations <em>\u00e0 caract\u00e8re \u00e9conomique<\/em> au secteur de l\u2019\u00c9conomie sociale et solidaire<a href=\"#_ftn10\" name=\"_ftnref10\">[10]<\/a>. En effet, pour bon nombre de ces \u00ab <em>entreprises associatives<\/em> \u00bb<a href=\"#_ftn11\" name=\"_ftnref11\">[11]<\/a>, la r\u00e9alisation d\u2019activit\u00e9s \u00e9conomiques, voire commerciales, ne constitue qu\u2019un moyen au service d\u2019un but non lucratif, comme l\u2019a d\u2019ailleurs confirm\u00e9 le Conseil constitutionnel : \u00ab <em>[\u2026] le principe, constitutionnellement garanti, de libert\u00e9 d\u2019association n\u2019interdit pas aux associations de se procurer les ressources n\u00e9cessaires \u00e0 la r\u00e9alisation de leur but, qui ne peut \u00eatre le partage de b\u00e9n\u00e9fices entre leurs membres, par l\u2019exercice d\u2019activit\u00e9s lucratives [\u2026]<\/em> \u00bb<a href=\"#_ftn12\" name=\"_ftnref12\">[12]<\/a>.<\/p>\n<h4><strong>Une association \u00ab\u00a0\u00e0 but non lucratif\u00a0\u00bb peut exercer des activit\u00e9s \u00e9conomiques ou commerciales<\/strong><\/h4>\n<p>En droit fiscal, bien que le raisonnement soit autonome, la distinction possible entre activit\u00e9 \u00e9conomique et commerciale\/lucrative r\u00e9v\u00e9l\u00e9e depuis l\u2019instruction fiscale du 15 septembre 1998<a href=\"#_ftn13\" name=\"_ftnref13\">[13]<\/a>, conforte un peu plus encore ce rapport original que les associations entretiennent avec le monde des affaires. En effet, toute association peut exercer des activit\u00e9s commerciales lucratives pour compl\u00e9ter ses ressources et boucler ainsi son budget. N\u00e9anmoins, ces activit\u00e9s doivent demeurer accessoires pour pouvoir b\u00e9n\u00e9ficier de la franchise commerciale dont le seuil est limit\u00e9, pour 2018, \u00e0 62.250 euros par ann\u00e9e civile<a href=\"#_ftn14\" name=\"_ftnref14\">[14]<\/a>. Et pour \u00e9viter tout risque de globalisation fiscale, ces groupements, \u00e0 l\u2019instar des fondations et fonds de dotation, doivent <a href=\"http:\/\/www.isbl-consultants.fr\/plaidoyer-faveur-de-lentreprise-associative\/#note21\">proc\u00e9der par voie de sectorisation[15], voire de filialisation[16]<\/a>, en cas de d\u00e9passement de ce seuil avant que les activit\u00e9s lucratives ne deviennent pr\u00e9pond\u00e9rantes.<\/p>\n<p>En parall\u00e8le, les associations peuvent s\u2019adonner sans r\u00e9serve \u2013 c\u2019est-\u00e0-dire quel que soit le montant du chiffre d\u2019affaires r\u00e9alis\u00e9 \u2013 \u00e0 des activit\u00e9s \u00e9conomiques jug\u00e9es hors champ concurrentiel, en particulier lorsque ces derni\u00e8res pr\u00e9sentent une utilit\u00e9 sociale<a href=\"#_ftn17\" name=\"_ftnref17\">[17]<\/a>. Tel est le cas d\u00e8s lors que les crit\u00e8res principaux du \u00ab<em> produit<\/em> \u00bb propos\u00e9 par l\u2019organisme, du \u00ab<em> public<\/em> \u00bb b\u00e9n\u00e9ficiaire du prix pratiqu\u00e9 &#8211; qui devra \u00eatre \u00ab\u00a0<em>nettement inf\u00e9rieur \u00e0 celui du march\u00e9<\/em>\u00a0\u00bb &#8211; et de l\u2019\u00ab <em>affectation des exc\u00e9dents<\/em> \u00bb sont remplis<a href=\"#_ftn18\" name=\"_ftnref18\">[18]<\/a>. S\u2019agissant de ce dernier crit\u00e8re, la doctrine fiscale a d\u2019ailleurs r\u00e9affirm\u00e9 le principe selon lequel \u00ab<em> il est l\u00e9gitime qu\u2019un organisme non lucratif d\u00e9gage, dans le cadre de son activit\u00e9, des exc\u00e9dents, reflets d\u2019une gestion saine et prudente<\/em> \u00bb<a href=\"#_ftn19\" name=\"_ftnref19\">[19]<\/a>. Dans cette hypoth\u00e8se, le secteur associatif pourra non seulement d\u00e9gager des exc\u00e9dents sans aucune limite mais pourra en outre conserver son statut d\u2019organisme \u00e0 but non lucratif, c\u2019est-\u00e0-dire de non assujetti aux imp\u00f4ts commerciaux (imp\u00f4t sur les soci\u00e9t\u00e9s, taxe sur la valeur ajout\u00e9e, et contribution \u00e9conomique territoriale).<\/p>\n<p>En d\u00e9finitive, le champ \u00e9conomique peut parfaitement constituer un \u00ab\u00a0<em>terrain de jeu<\/em>\u00a0\u00bb pour les associations, sans craindre une d\u00e9naturation de leur mode de fonctionnement comme de leur statut fiscal originel. Seul le recours syst\u00e9matique \u00e0 la participation financi\u00e8re des membres &#8211; dans des conditions identiques au secteur concurrentiel &#8211; et une g\u00e9n\u00e9ralisation de la commande publique (sans int\u00e9gration de clauses sociales<a href=\"#_ftn20\" name=\"_ftnref20\">[20]<\/a>) &#8211; au d\u00e9triment de la subvention \u2013 risquent d\u2019entra\u00eener pour ces nouveaux op\u00e9rateurs \u00e9conomiques une certaine forme de banalisation de leur action.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Colas Amblard \u2013 Docteur en droit<\/strong><\/p>\n<p><strong>Avocat associ\u00e9 Cabinet NPS consulting<\/strong><\/p>\n<p><strong>Charg\u00e9 d\u2019enseignement \u00e0 l\u2019Universit\u00e9 Jean Moulin Lyon III<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>R\u00e9f\u00e9rences :<\/strong><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Dossier \u00ab Exc\u00e9dents et non-lucrativit\u00e9 \u2013 Le b\u00e9n\u00e9fice du doute \u00bb, JA n\u00b0 580\/2018, p. 17.<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Cons. const., d\u00e9cis. n\u00b0 2006-20\/21 du 20 juill. 2006 ; Cons. const., d\u00e9cis. n\u00b0 2006\/22 du 26 oct. 2006.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> CJCE 23 avr. 1991, aff. C-41\/90 ; CJCE 16 nov. 1995, aff. C-244\/94 ;TPICE 12 d\u00e9c. 2006, aff. T-155\/04.<\/p>\n<p><a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> Com. 19 janv. 1988, no 85-18.443 ;\u00a0v. \u00e9gal. Com. 1er mars 1994, no 92-13.529.<\/p>\n<p><a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> Com. 13 mai 1970, n\u00b0 69-11.268.<\/p>\n<p><a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> Com. 17 mars 1981, n\u00b0 79-14.117.<\/p>\n<p><a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> R. Brichet, \u00ab Une association peut-elle \u00eatre une personne morale de droit commer\u00e7ant ? \u00bb, JCP E 1988, nos 43-44, p. 336.<\/p>\n<p><a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a> CA Grenoble, 13 juin 2017, n\u00b014\/05081, JA no 568\/2017, p. 10.<\/p>\n<p><a href=\"#_ftnref9\" name=\"_ftn9\">[9]<\/a> C. Amblard, Activit\u00e9s \u00e9conomiques et commerciales des associations, Lamy associations, Etude 246.<\/p>\n<p><a href=\"#_ftnref10\" name=\"_ftn10\">[10]<\/a> L. n\u00b02014-856 du 31 juill. 2014 (JO du 1<sup>er<\/sup> ao\u00fbt), art. 1.<\/p>\n<p><a href=\"#_ftnref11\" name=\"_ftn11\">[11]<\/a> S. Castro et N. Alix, L\u2019entreprise associative\u00a0: aspects juridiques de l\u2019intervention \u00e9conomique des associations, Ed. Economica, 1990.<\/p>\n<p><a href=\"#_ftnref12\" name=\"_ftn12\">[12]<\/a> Cons. const., d\u00e9cis. n\u00b0 84-176 DC\u00a0du 25 juill. 1984.<\/p>\n<p><a href=\"#_ftnref13\" name=\"_ftn13\">[13]<\/a> Instr. du 15 sept. 1998, BOI 4 H-5-98<\/p>\n<p><a href=\"#_ftnref14\" name=\"_ftn14\">[14]<\/a> BOFiP-Imp\u00f4ts, BOI-IS-CHAMP-10-50- 20-20 du 4 avr. 2018.<\/p>\n<p><a href=\"#_ftnref15\" name=\"_ftn15\">[15]<\/a> BOFiP-Imp\u00f4ts, BOI-IS-CHAMP-10-50- 20-10 du 1er avr. 2015, \u00a7 120 \u00e0 550.<\/p>\n<p><a href=\"#_ftnref16\" name=\"_ftn16\">[16]<\/a> Ibid., \u00a7 560 \u00e0 770.<\/p>\n<p><a href=\"#_ftnref17\" name=\"_ftn17\">[17]<\/a> BOFiP-Imp\u00f4ts, BOI-IS-CHAMP-10-50- 10-20 du 7 juin 2017, \u00a7 590 \u00e0 620.<\/p>\n<p><a href=\"#_ftnref18\" name=\"_ftn18\">[18]<\/a> Ibid., \u00a7 630.<\/p>\n<p><a href=\"#_ftnref19\" name=\"_ftn19\">[19]<\/a> Ibid.<\/p>\n<p><a href=\"#_ftnref20\" name=\"_ftn20\">[20]<\/a> L. n\u00b02014-856 pr\u00e9c., art. 13.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assur\u00e9ment, l\u2019un des faits associatifs les plus marquants de cette nouvelle \u00e9tude r\u00e9side dans le \u00ab\u00a0boom\u00a0\u00bb des recettes d\u2019activit\u00e9s associatives, puisque celles-ci sont pass\u00e9es de 49% \u00e0 66% en part de budget cumul\u00e9 du secteur associatif entre 2005 et 2017. Les raisons de ce ph\u00e9nom\u00e8ne sont connues\u00a0: diminution des subventions, augmentation du recours \u00e0 la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[283],"tags":[365,63,259,339,15,130],"class_list":["post-2562","post","type-post","status-publish","format-standard","hentry","category-article","tag-activite-economique","tag-activites-commerciales","tag-association-et-avocat","tag-avocat-specialise-en-droit-associatif","tag-economie-sociale-et-solidaire","tag-entreprise-associative"],"_links":{"self":[{"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/posts\/2562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/comments?post=2562"}],"version-history":[{"count":5,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/posts\/2562\/revisions"}],"predecessor-version":[{"id":2567,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/posts\/2562\/revisions\/2567"}],"wp:attachment":[{"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/media?parent=2562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/categories?post=2562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.npsconsulting-avocats.fr\/NPS\/wp-json\/wp\/v2\/tags?post=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}